{"id":6,"date":"2019-08-18T17:27:37","date_gmt":"2019-08-18T10:27:37","guid":{"rendered":"https:\/\/www.hongthai.co.th\/?page_id=6"},"modified":"2026-07-30T15:22:39","modified_gmt":"2026-07-30T08:22:39","slug":"%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%ab%e0%b8%a5%e0%b8%b1%e0%b8%81","status":"publish","type":"page","link":"https:\/\/www.hongthai.co.th\/th\/","title":{"rendered":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01"},"content":{"rendered":"\n\t<section class=\"section banner--section dark\" id=\"section_168709288\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1950\" height=\"762\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/banner-home.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\t<div id=\"gap-1431462218\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1431462218 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1112360045\">\r\n\r\n\n\t<div id=\"col-1627608937\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"text-2379008927\" class=\"text\">\n\t\t\r\n<h1 class=\"uppercase\" style=\"margin-bottom: 0; font-size: 280%;\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22<\/h1>\r\n\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\r\n\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e41\u0e1a\u0e23\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\r\n\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 300 \u0e41\u0e1a\u0e23\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 40 \u0e1b\u0e35\r\n\r\n\t\t\n<style>\n#text-2379008927 {\n  font-size: 1.45rem;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1814006170\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"slider-wrapper relative\" id=\"slider-329105764\" >\n    <div class=\"slider slider-type-fade slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : false,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2095518546\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1473\" height=\"555\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-box.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-box.png 1473w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-box-300x113.png 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-box-1024x386.png 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-box-768x289.png 768w\" sizes=\"auto, (max-width: 1473px) 100vw, 1473px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2095518546 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_447236478\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1473\" height=\"555\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-food-packaging.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-food-packaging.png 1473w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-food-packaging-300x113.png 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-food-packaging-1024x386.png 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/slider-food-packaging-768x289.png 768w\" sizes=\"auto, (max-width: 1473px) 100vw, 1473px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_447236478 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_168709288 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: #ef7d00;\n}\n#section_168709288 .section-bg-overlay {\n  background-color: rgba(19, 13, 67, 0.8);\n}\n#section_168709288 .section-bg img {\n  object-position: 50% 50%;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_401476966\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\t<div class=\"ux-shape-divider ux-shape-divider--bottom ux-shape-divider--style-waves-opacity\">\n\t\t<svg viewBox=\"0 0 1000 300\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\">\n    <path class=\"ux-shape-fill\" d=\"M0 300L-1 69.71C216 57 299.47 198.86 403 226C506 253 577 196 660 197C740 198 790.09 234.07 874 267C935.23 291 982 282.61 1000 277.61V300H0Z\"\/>\n    <path class=\"ux-shape-fill\" opacity=\"0.5\" d=\"M1 265.094L0 50.5C217 37.79 300.47 186.36 404 213.5C507 240.5 578 196.5 661 197.5C741 198.5 787.59 239.57 871.5 272.5C932.73 296.5 980.5 284.5 998.5 279.5V298.5L1 265.094Z\"\/>\n    <path class=\"ux-shape-fill\" opacity=\"0.15\" d=\"M0.999878 244.094L-0.00012207 27C217 14.29 300.47 173.86 404 201C507 228 578 196 661 197C741 198 787.59 243.07 871.5 276C932.73 300 980.5 284.5 998.5 279.5V299L0.999878 244.094Z\"\/>\n<\/svg>\n\n\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_401476966 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 100px;\n  background-color: #ef7d00;\n}\n#section_401476966 .ux-shape-divider--bottom svg {\n  height: 50px;\n  --divider-width: 100%;\n}\n@media (min-width:550px) {\n  #section_401476966 .ux-shape-divider--bottom svg {\n    height: 150px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_972304681\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row align-middle\"  id=\"row-1524593177\">\r\n\r\n\n\t<div id=\"col-527614137\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1477692290\">\r\n\r\n\n\t<div id=\"col-1869572044\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover icon-blue  has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"148\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-convenient.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h3 class=\"purple\">\u0e2a\u0e30\u0e14\u0e27\u0e01<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-436084761\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover icon-blue  has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"148\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-good-quality.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h3 class=\"purple\">\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1543165349\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover icon-blue  has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"148\" height=\"148\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-fast.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h3 class=\"purple\">\u0e07\u0e32\u0e19\u0e14\u0e35\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1925231725\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"is-divider divider clearfix\" style=\"max-width:100px;background-color:rgb(239, 125, 0);\"><\/div>\r\n<p class=\"orange\" style=\"font-size: 220%; font-weight: 500;\"><span class=\"purple\">\u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d <\/span>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33<\/p>\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1705141086\" class=\"col medium-6 small-12 large-6 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_384905375\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"766\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/product-oct.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/product-oct.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/product-oct-300x225.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/product-oct-768x577.jpg 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_384905375 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_972304681 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section bg-style-1\" id=\"section_1868807098\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-services.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-1.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07 <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>Our service | Hong thai<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n<div class=\"row align-equal align-center mt--80\"  id=\"row-920632178\">\r\n\r\n\n\t<div id=\"col-390980159\" class=\"col padding rounded medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-178872913\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-178872913 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:30%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-online-ordering.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-online-ordering.png 230w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-online-ordering-150x150.png 150w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4 class=\"purple\">Client brief and Online ordering<\/h4>\r\n<h4 class=\"orange\">\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27<\/h4>\r\n<div class=\"is-divider divider clearfix\" style=\"margin-top:1em;margin-bottom:1em;max-width:60px;background-color:rgb(48, 39, 131);\"><\/div>\r\n\r\n\u0e23\u0e30\u0e1a\u0e1a ERP \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 \u0e17\u0e35\u0e48 \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f \u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e31\u0e49\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e09\u0e31\u0e1a\u0e44\u0e27 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a SERVER \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e19\u0e23 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e25\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-508335981\" class=\"col padding rounded medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-1148638562\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1148638562 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:30%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-packaging-design.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-packaging-design.png 230w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-packaging-design-150x150.png 150w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4 class=\"purple\">Packaging Design<\/h4>\r\n<h4 class=\"orange\">\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<\/h4>\r\n<div class=\"is-divider divider clearfix\" style=\"margin-top:1em;margin-bottom:1em;max-width:60px;background-color:rgb(48, 39, 131);\"><\/div>\r\n\r\n\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e2d\u0e23\u0e40\u0e27\u0e22\u0e4c Artios \u0e1c\u0e19\u0e27\u0e01\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c UV DIGITAL FLAT BED \u0e02\u0e2d\u0e07\u0e1f\u0e39\u0e08\u0e34 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e43\u0e2b\u0e49 \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c CMYK + \u0e2a\u0e35\u0e02\u0e32\u0e27 \u0e44\u0e14\u0e49 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e19\u0e32\u0e17\u0e35 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a Profile \u0e2a\u0e35\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a (Substrate) \u0e19\u0e31\u0e49\u0e19\u0e46\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1431078605\" class=\"col padding rounded medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-1161480924\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1161480924 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:30%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-printing-finishing.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-printing-finishing.png 230w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-printing-finishing-150x150.png 150w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4 class=\"purple\">Printing and Finishing<\/h4>\r\n<h4 class=\"orange\">\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22<\/h4>\r\n<div class=\"is-divider divider clearfix\" style=\"margin-top:1em;margin-bottom:1em;max-width:60px;background-color:rgb(48, 39, 131);\"><\/div>\r\n\r\n\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22 \u0e21\u0e35\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e30\u0e1a\u0e1a Offset 6 \u0e2a\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e49\u0e19\u0e04\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c UV DIGITAL 4 \u0e2a\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e02\u0e32\u0e27 \u0e23\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-41137758\" class=\"col padding rounded medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-1866912262\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1866912262 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:30%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"230\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-on-time-delivery.png\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-on-time-delivery.png 230w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-on-time-delivery-150x150.png 150w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4 class=\"purple\">On Time Delivery<\/h4>\r\n<h4 class=\"orange\">\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e07\u0e32\u0e19\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e15\u0e23\u0e07\u0e40\u0e27\u0e25\u0e32<\/h4>\r\n<div class=\"is-divider divider clearfix\" style=\"margin-top:1em;margin-bottom:1em;max-width:60px;background-color:rgb(48, 39, 131);\"><\/div>\r\n\r\n\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e1a\u0e1a Real Time \u0e43\u0e19 \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1a\u0e1a ONLINE \u0e17\u0e33\u0e43\u0e2b\u0e49 \u0e17\u0e32\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e21\u0e31\u0e48\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e01\u0e33\u0e2b\u0e19\u0e14\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\t<div id=\"gap-291304182\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-291304182 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1868807098 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section bg-style-2\" id=\"section_161910621\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-title-welcome.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-2.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e22\u0e34\u0e19\u0e14\u0e35\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22 | Hong Thai<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n<div class=\"row align-center mt--80\"  id=\"row-1322349630\">\r\n\r\n\n\t<div id=\"col-582875231\" class=\"col padding rounded medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 255, 255);\" >\n\t\t\t\n\t\t\t\r\n\r\n\n  <div class=\"banner has-hover border-white rounded\" id=\"banner-714660111\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"282\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-about-video-1024x283.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \r\n\r\n   <div id=\"text-box-480997056\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=pRwqexq8mzE\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n<h3 class=\"uppercase orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/h3>\r\n<p style=\"font-size: 120%;\">\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e01\u0e25\u0e48\u0e2d\u0e07 offset\r\nFood Packaging \u0e41\u0e25\u0e30\u0e41\u0e1c\u0e07\u0e44\u0e02\u0e48 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e02\u0e48\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\r\nOne-stop service in the paper packaging industy\u200b<\/p>\r\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-480997056 {\n  width: 60%;\n}\n#text-box-480997056 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \r\n\r\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-714660111 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n#banner-714660111 .overlay {\n  background-color: rgba(48, 39, 131, 0.3);\n}\n#banner-714660111 .banner-bg img {\n  object-position: 51% 40%;\n}\n<\/style>\n  <\/div>\n\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n<div class=\"row\"  id=\"row-1001582629\">\r\n\r\n\n\t<div id=\"col-1546140701\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"stack-862676625\" class=\"stack welcome--stack stack-row justify-center items-center\">\n\t\t\r\n\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"99\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-about-1.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e35 <strong>2531<\/strong><\/h4>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"99\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-about-2.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4>\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e42\u0e0b\u0e19\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 <strong>40 \u0e44\u0e23\u0e48<\/strong>(64,000 \u0e15\u0e23\u0e21.)<\/h4>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"99\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-about-3.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4>\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e42\u0e0b\u0e19\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 <strong>32 \u0e44\u0e23\u0e48<\/strong> (51,200 \u0e15\u0e23\u0e21.)<\/h4>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"99\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-about-4.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4>\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 <strong>4,000+<\/strong> \u0e15\u0e31\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e14\u0e37\u0e2d\u0e19<\/h4>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:70%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"99\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-about-5.png\" class=\"attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h4>\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 <strong>500+<\/strong><\/h4>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t\n<style>\n#stack-862676625 > * {\n  --stack-gap: 1.5rem;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\t<div id=\"gap-804462073\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-804462073 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row align-center\"  id=\"row-1346462938\">\r\n\r\n\n\t<div id=\"col-1917248259\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"row align-middle\"  id=\"row-944082362\">\r\n\r\n\n\t<div id=\"col-518534051\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<img decoding=\"async\" style=\"max-width: 250px;\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/hongthai-logo.png\" \/>\r\n\r\n\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e19\u0e32\u0e21 <span class=\"orange\">\u201c\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u201d \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c<\/span> \u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e21\u0e32\u0e01\u0e27\u0e48\u0e32 42 \u0e1b\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1c\u0e48\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e2d\u0e1f\u0e40\u0e0b\u0e47\u0e17\u0e1b\u0e30\u0e01\u0e1a\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1c\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e22\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 (PULP MOLD) \u0e41\u0e1c\u0e07\u0e44\u0e02\u0e48\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 Food Packaging\r\n\r\n\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\r\n<p class=\"purple\"><strong>\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1c\u0e48\u0e19\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 3 \u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15<\/strong><\/p>\r\n\u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e30\u0e1a\u0e1a FLEXO \u0e2a\u0e35\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a Pre Print \u0e41\u0e25\u0e30 Post Print \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c OFFSET \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e1a\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 DIE CUT \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\r\n\r\n<a href=\"https:\/\/www.hongthai.co.th\/about-us\/\" class=\"button secondary\" style=\"border-radius:4px;\">\n\t\t<span>\u0e14\u0e39\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1368893100\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover border-white x md-x lg-x y md-y lg-y\" id=\"image_1807686118\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1807686118 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_161910621 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section bg-style-1 cert--section\" id=\"section_935006048\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up hide-bg dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url();\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-3.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e43\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>Our certifications | Hong Thai<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t<div id=\"gap-349864429\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-349864429 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\n  \n    <div class=\"row certificate--gallery lightbox-multi-gallery large-columns-4 medium-columns-3 small-columns-2\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-1.jpg\" title=\"ISO 9001:2015 Certification\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-1-212x300.jpg\" class=\"certificate--gallery\" alt=\"ISO 9001:2015 Certification\" ids=\"4031,4034,4037,4040\" style=\"normal\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-1-212x300.jpg 212w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-1.jpg 336w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>ISO 9001:2015 Certification<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-2.jpg\" title=\"Codex HACCP &amp; GHPs\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-2-212x300.jpg\" class=\"certificate--gallery\" alt=\"Codex HACCP &amp; GHPs\" ids=\"4031,4034,4037,4040\" style=\"normal\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-2-212x300.jpg 212w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-2.jpg 336w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Codex HACCP &amp; GHPs<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-3.jpg\" title=\"Food safety management systems - ISO 22000:2018\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-3-212x300.jpg\" class=\"certificate--gallery\" alt=\"Food safety management systems - ISO 22000:2018\" ids=\"4031,4034,4037,4040\" style=\"normal\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-3-212x300.jpg 212w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-3.jpg 336w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Food safety management systems - ISO 22000:2018<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-4.jpg\" title=\"FSC-STD-40-004 V3-1 Certification\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-4-212x300.jpg\" class=\"certificate--gallery\" alt=\"FSC-STD-40-004 V3-1 Certification\" ids=\"4031,4034,4037,4040\" style=\"normal\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-4-212x300.jpg 212w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/cert-4.jpg 336w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>FSC-STD-40-004 V3-1 Certification<\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\r\n\r\n\t<div id=\"gap-996949775\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-996949775 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_935006048 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_1077667526\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-step.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-4.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07 <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>Production Process of Hong Thai<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n<div class=\"row align-center\" style=\"max-width:1400px\" id=\"row-1221279110\">\r\n\r\n\n\t<div id=\"col-183869035\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n        <div class=\"step-ht--wrap\">\n            <div class=\"step-ht--number\" style=\"background-color: var(--fs-color-secondary);\">\n                <span>1<\/span>\n            <\/div>\n            <div class=\"step-ht--content\">\n                <div class=\"step-ht--text\">\n                    <span>\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e22\u0e49\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e21\u0e49\u0e27\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e42\u0e01\u0e14\u0e31\u0e07\u0e23\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b<\/span>\n                <\/div>\n                <div class=\"step-ht--image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-1.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-1-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-361629008\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n        <div class=\"step-ht--wrap\">\n            <div class=\"step-ht--number\" style=\"background-color: var(--fs-color-primary);\">\n                <span>2<\/span>\n            <\/div>\n            <div class=\"step-ht--content\">\n                <div class=\"step-ht--text\">\n                    <span>\u0e2d\u0e22\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07<\/span>\n                <\/div>\n                <div class=\"step-ht--image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-2-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-384609470\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n        <div class=\"step-ht--wrap\">\n            <div class=\"step-ht--number\" style=\"background-color: var(--fs-color-secondary);\">\n                <span>3<\/span>\n            <\/div>\n            <div class=\"step-ht--content\">\n                <div class=\"step-ht--text\">\n                    <span>\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e48\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32<\/span>\n                <\/div>\n                <div class=\"step-ht--image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-3.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-3-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-408549232\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n        <div class=\"step-ht--wrap\">\n            <div class=\"step-ht--number\" style=\"background-color: var(--fs-color-primary);\">\n                <span>4<\/span>\n            <\/div>\n            <div class=\"step-ht--content\">\n                <div class=\"step-ht--text\">\n                    <span>\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e34\u0e48\u0e21 \u0e16\u0e49\u0e27\u0e22 \u0e41\u0e01\u0e49\u0e27 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/span>\n                <\/div>\n                <div class=\"step-ht--image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-4.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-4-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-607509685\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n        <div class=\"step-ht--wrap\">\n            <div class=\"step-ht--number\" style=\"background-color: var(--fs-color-secondary);\">\n                <span>5<\/span>\n            <\/div>\n            <div class=\"step-ht--content\">\n                <div class=\"step-ht--text\">\n                    <span>\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a Offset<\/span>\n                <\/div>\n                <div class=\"step-ht--image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"513\" height=\"344\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-5.jpg 513w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/image-step-5-300x201.jpg 300w\" sizes=\"auto, (max-width: 513px) 100vw, 513px\" \/>                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1077667526 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_1430908687\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\t<div id=\"gap-1346083376\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1346083376 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row\"  id=\"row-1097708401\">\r\n\r\n\n\t<div id=\"col-688409919\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-3.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-3.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-3-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.5)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=A6exjS1Sfc0\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n\r\n8 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e02\u0e2d\u0e07\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-53440564\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-1.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-1-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.7)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=8WCiJGcwQCc\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n\r\n\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e42\u0e25\u0e42\u0e01\u0e49\r\n\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-373412671\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-2.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-2-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.7)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=lZZNy6JzPKU\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n\r\n\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e41\u0e1a\u0e1a\u0e1d\u0e32\u0e0a\u0e19 RSC (Regular Slotted Container)\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1430908687 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(238, 238, 238);\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section bg-style-3\" id=\"section_264748609\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n\t<div id=\"gap-891682500\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-891682500 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t<div id=\"gap-877570074\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-877570074 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row dowload-file--row\"  id=\"row-625134701\">\r\n\r\n\n\t<div id=\"col-1790486189\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover sample  has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"566\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-1.jpg 805w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-1-300x211.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-1-768x540.jpg 768w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h3 style=\"margin-bottom: 15px;\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e25\u0e48\u0e2d\u0e07\r\n\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e48\u0e2d\u0e07<\/h3>\r\n<p class=\"uppercase\"><small>Sample and Design Box | <span class=\"orange\">Hong Thai<\/span><\/small><\/p>\r\n<a href=\"https:\/\/www.hongthai.co.th\/web2024\/wp-content\/uploads\/2019\/09\/FEFCO_PL.pdf\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t<i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i>\t<span>Download File<\/span>\n\t<\/a>\n\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1229065564\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover sample  has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"566\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-2.jpg 805w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-2-300x211.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/exsample-2-768x540.jpg 768w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n<h3 style=\"margin-bottom: 15px;\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\r\n\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e48\u0e2d\u0e07<\/h3>\r\n<p class=\"uppercase\"><small>Sample box for food And design | <span class=\"orange\">Hong Thai<\/span><\/small><\/p>\r\n<a href=\"https:\/\/www.hongthai.co.th\/web2024\/wp-content\/uploads\/2019\/09\/Product-List-Hong-Thai-2019.pdf\" target=\"_blank\" class=\"button white\" rel=\"noopener\" style=\"border-radius:99px;\">\n\t<i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i>\t<span>Download File<\/span>\n\t<\/a>\n\r\n\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\t<div id=\"gap-754076009\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-754076009 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_264748609 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_206326434\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2025\/01\/home-banner-events-2.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-5.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e2d\u0e2d\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>Hong Thai Events<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t<div id=\"gap-308159087\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-308159087 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n<div class=\"row\"  id=\"row-1221885255\">\r\n\r\n\n\t<div id=\"col-588074689\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-1.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-1-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.6)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=jwYqnvZ7ldw\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n<h3>Thaifex-Anuga Asia 2024<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1891877664\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-2.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-2.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-2-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.6)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=GQHrXfWAPxw\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n<h3>Thaifex-Anuga Asia 2023<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-171808550\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"box has-hover rounded-12  has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"379\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-3.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-3.jpg 585w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/video-event-3-300x194.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:rgba(48, 39, 131, 0.6)\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\r\n\r\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=UM6TEQ51fmM\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\r\n<h3>Thaifex-Anuga Asia 2022<\/h3>\r\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_206326434 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_643785377\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-title-clients.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-6.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 42 \u0e1b\u0e35<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n<div class=\"row\"  id=\"row-427412327\">\r\n\r\n\n\t<div id=\"col-251997706\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-1668919473\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1668919473 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\n  \n    <div class=\"row clients--gallery lightbox-multi-gallery large-columns-7 medium-columns-7 small-columns-3\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-fb-battery.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-fb-battery.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-ikea.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-ikea.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-lazada.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-lazada.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-m150.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-m150.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-thaipost.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-thaipost.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-vt.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-vt.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"\" href=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-yumyum.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"124\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/logo-yumyum.png\" class=\"clients--gallery\" alt=\"\" ids=\"4133,4136,4139,4142,4145,4148,4151\" style=\"none\" columns=\"7\" columns__sm=\"3\" columns__md=\"7\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_643785377 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section bg-style-2\" id=\"section_1872787369\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-title-blog.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-7.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>Paper <span class=\"orange\">Knowledge<\/span><br><small>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n\t<div id=\"gap-789555126\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-789555126 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1 has-shadow row-box-shadow-1\" >\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/3-%e0%b9%80%e0%b8%84%e0%b8%a5%e0%b9%87%e0%b8%94%e0%b8%a5%e0%b8%b1%e0%b8%9a-%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b9%81%e0%b8%9a%e0%b8%a3%e0%b8%99%e0%b8%94%e0%b9%8c%e0%b8%aa%e0%b8%b4\/\" class=\"plain\" aria-label=\"3 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a-\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07-\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a-\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07-\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a-\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07-\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a-\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07-\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a-\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07-\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/3-%e0%b9%80%e0%b8%84%e0%b8%a5%e0%b9%87%e0%b8%94%e0%b8%a5%e0%b8%b1%e0%b8%9a-%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b9%81%e0%b8%9a%e0%b8%a3%e0%b8%99%e0%b8%94%e0%b9%8c%e0%b8%aa%e0%b8%b4\/\" class=\"plain\">3 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e1b\u0e31\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e21\u0e35\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e02...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/3-%e0%b9%80%e0%b8%84%e0%b8%a5%e0%b9%87%e0%b8%94%e0%b8%a5%e0%b8%b1%e0%b8%9a-%e0%b8%aa%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%87%e0%b9%81%e0%b8%9a%e0%b8%a3%e0%b8%99%e0%b8%94%e0%b9%8c%e0%b8%aa%e0%b8%b4\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%84%e0%b8%b4%e0%b8%94-%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%b8%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91\/\" class=\"plain\" aria-label=\"\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14-\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23-\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-1-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14-\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23-\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-1-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14-\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23-\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-1-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14-\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23-\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-1-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14-\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23-\u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%84%e0%b8%b4%e0%b8%94-%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%b8%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91\/\" class=\"plain\">\u0e27\u0e34\u0e18\u0e35\u0e04\u0e34\u0e14 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e43\u0e2b\u0e49\u0e42\u0e14\u0e19\u0e43\u0e08\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e22\u0e2d\u0e14\u0e02\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%84%e0%b8%b4%e0%b8%94-%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%a3%e0%b8%88%e0%b8%b8%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-types-color-influence\/\" class=\"plain\" aria-label=\"3 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35-\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07-1-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35-\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07-1-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35-\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07-1-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35-\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07-1-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35-\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07-1.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-types-color-influence\/\" class=\"plain\">3 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e35\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e2b...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-types-color-influence\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-tips\/\" class=\"plain\" aria-label=\"3 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49-\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49-\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49-\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49-\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/3-\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49-\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-tips\/\" class=\"plain\">3 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-tips\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-marketing-fix\/\" class=\"plain\" aria-label=\"4 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/4-\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14-\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/4-\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14-\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/4-\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14-\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/4-\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14-\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/4-\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14-\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-marketing-fix\/\" class=\"plain\">4 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e1a\u0e40\u0e08\u0e2d \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-marketing-fix\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-bounce box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:66%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-images\/\" class=\"plain\" aria-label=\"\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e-\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e-\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-300x200.jpg 300w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e-\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-768x512.jpg 768w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e-\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c-1024x683.jpg 1024w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2019\/09\/\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e-\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-images\/\" class=\"plain\">\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e1e \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e2a\u0e35...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hongthai.co.th\/th\/news-and-blog\/packaging-design-images\/\" class=\"button  is-outline is-small mb-0\">\n\t\t\t\t\t\t\t\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\r\n\r\n<div class=\"row\"  id=\"row-950381921\">\r\n\r\n\n\t<div id=\"col-804095652\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n<a href=\"https:\/\/www.hongthai.co.th\/th\/category\/news-and-blog\/\" class=\"button primary\" style=\"border-radius:4px;\">\n\t\t<span>\u0e14\u0e39\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1872787369 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\r\n\n\t<section class=\"section\" id=\"section_305940224\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n        <div class=\"ht-wrap border-br-up  dark\">\n            <div class=\"ht-title-bg\">\n                <div class=\"ht-title-bg-right\" style=\"background-image: url(https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/bg-title-product-2.jpg);\"><\/div>\n                <div class=\"ht-title-bg-left\"><\/div>\n            <\/div>\n            <div class=\"container\">\n                <div class=\"ht-title-wrap\">\n                    <div class=\"ht-title-inner\">\n                        <div class=\"ht-icon\">\n                            <span><img loading=\"lazy\" decoding=\"async\" width=\"60\" height=\"60\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/icon-title-8.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/span>\n                        <\/div>\n                        <div class=\"ht-title\">\n                            <h1>\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07 <span class=\"orange\">\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\u0e2f<\/span><br><small>Product of Hong Thai<\/small><\/h1>                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\r\n\r\n<div class=\"row row-full-width\"  id=\"row-1944423159\">\r\n\r\n\n\t<div id=\"col-1394106605\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div id=\"gap-419540045\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-419540045 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\n  \n    <div id=\"gallery-959282575\" class=\"row product--gallery lightbox-multi-gallery large-columns-6 medium-columns-3 small-columns-2 row-small row-full-width row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-1-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-1-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-1.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-1.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-1-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e21\u0e49\u0e27\u0e19\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-1-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-1.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e21\u0e49\u0e27\u0e19<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-1-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-1-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-1.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-1.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e27\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-1-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-1-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-1.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-2-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e19\u0e02\u0e2d\u0e07\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-2-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-2.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e19\u0e02\u0e2d\u0e07<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-2-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-2-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-2.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-2-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c KA KT\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-2-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-2.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c KA KT<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-2-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-2-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-2.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-2-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-2-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-2.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-2-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c Kerry\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-2-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-2.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c Kerry<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-3-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e16\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e41\u0e25\u0e30\u0e16\u0e49\u0e27\u0e22\u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-3-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-3.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e16\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e41\u0e25\u0e30\u0e16\u0e49\u0e27\u0e22\u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-3-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e19\u0e02\u0e2d\u0e07\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-3-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-3.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e19\u0e02\u0e2d\u0e07<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-3.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-3-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e17\u0e23\u0e07\u0e22\u0e32\u0e27\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-3-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-3.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e17\u0e23\u0e07\u0e22\u0e32\u0e27<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-3.jpg\" class=\"product--gallery\" alt=\"\u0e0a\u0e32\u0e21\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e0a\u0e32\u0e21\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-3-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e41\u0e01\u0e49\u0e27\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-3-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-3.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e41\u0e01\u0e49\u0e27\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-4-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1d\u0e32\u0e40\u0e01\u0e22 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e1b\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-4-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-1-4.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1d\u0e32\u0e40\u0e01\u0e22 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e1b<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-4-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e16\u0e32\u0e14\u0e2b\u0e25\u0e38\u0e21\u0e43\u0e2a\u0e48\u0e41\u0e01\u0e49\u0e27\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-4-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-4-4.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e16\u0e32\u0e14\u0e2b\u0e25\u0e38\u0e21\u0e43\u0e2a\u0e48\u0e41\u0e01\u0e49\u0e27<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-4-229x300.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e02\u0e48 \u0e41\u0e1c\u0e07\u0e44\u0e02\u0e48\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-4-229x300.jpg 229w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-5-4.jpg 296w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e02\u0e48 \u0e41\u0e1c\u0e07\u0e44\u0e02\u0e48\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"285\" height=\"300\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-4-285x300.jpg\" class=\"product--gallery\" alt=\"\u0e2b\u0e21\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" srcset=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-4-285x300.jpg 285w, https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-2-4.jpg 296w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e2b\u0e21\u0e27\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-3-4.jpg\" class=\"product--gallery\" alt=\"\u0e1e\u0e32\u0e40\u0e25\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e1e\u0e32\u0e40\u0e25\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"238\" src=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2024\/12\/p-6-4.jpg\" class=\"product--gallery\" alt=\"\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e1c\u0e25\u0e44\u0e21\u0e49\" ids=\"4154,4166,4178,4190,4202,4214,4169,4205,4181,4217,4157,4193,4208,4172,4160,4184,4196,4220,4163,4199,4211,4175,4187,4223\" style=\"normal\" lightbox=\"false\" type=\"masonry\" col_spacing=\"small\" columns=\"6\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e1c\u0e25\u0e44\u0e21\u0e49<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_305940224 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":5858,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hongthai.co.th\/th\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hongthai.co.th\/th\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T08:22:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2026\/07\/link-image-HT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/\",\"url\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/\",\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hongthai.co.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/link-image-HT.jpg\",\"datePublished\":\"2019-08-18T10:27:37+00:00\",\"dateModified\":\"2026-07-30T08:22:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hongthai.co.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/link-image-HT.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hongthai.co.th\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/link-image-HT.jpg\",\"width\":1200,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/\",\"name\":\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hongthai.co.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hongthai.co.th\/th\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22","og_url":"https:\/\/www.hongthai.co.th\/th\/","og_site_name":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22","article_modified_time":"2026-07-30T08:22:39+00:00","og_image":[{"width":1200,"height":631,"url":"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2026\/07\/link-image-HT.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hongthai.co.th\/th\/","url":"https:\/\/www.hongthai.co.th\/th\/","name":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01 - \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22","isPartOf":{"@id":"https:\/\/www.hongthai.co.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hongthai.co.th\/th\/#primaryimage"},"image":{"@id":"https:\/\/www.hongthai.co.th\/th\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2026\/07\/link-image-HT.jpg","datePublished":"2019-08-18T10:27:37+00:00","dateModified":"2026-07-30T08:22:39+00:00","breadcrumb":{"@id":"https:\/\/www.hongthai.co.th\/th\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hongthai.co.th\/th\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.hongthai.co.th\/th\/#primaryimage","url":"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2026\/07\/link-image-HT.jpg","contentUrl":"https:\/\/www.hongthai.co.th\/wp-content\/uploads\/2026\/07\/link-image-HT.jpg","width":1200,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/www.hongthai.co.th\/th\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hongthai.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01"}]},{"@type":"WebSite","@id":"https:\/\/www.hongthai.co.th\/th\/#website","url":"https:\/\/www.hongthai.co.th\/th\/","name":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07 Offset \u0e01\u0e25\u0e48\u0e2d\u0e07 Pre Print \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e14\u0e04\u0e31\u0e17 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO9001:2015 \u0e41\u0e25\u0e30 FSC:COC - \u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hongthai.co.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":34,"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":5860,"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/pages\/6\/revisions\/5860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/media\/5858"}],"wp:attachment":[{"href":"https:\/\/www.hongthai.co.th\/th\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}